{"id":1189,"count":1,"description":"","link":"https:\/\/selfhelpafrica.org\/ie\/tag\/management\/","name":"management","slug":"management","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>management Archives - Self Help Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/selfhelpafrica.org\/ie\/tag\/management\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"management Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/selfhelpafrica.org\/ie\/tag\/management\/\" \/>\n<meta property=\"og:site_name\" content=\"Self Help Africa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@selfhelpafrica\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/selfhelpafrica.org\\\/ie\\\/tag\\\/management\\\/\",\"url\":\"https:\\\/\\\/selfhelpafrica.org\\\/ie\\\/tag\\\/management\\\/\",\"name\":\"management Archives - Self Help Africa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/selfhelpafrica.org\\\/ie\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/selfhelpafrica.org\\\/ie\\\/tag\\\/management\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/selfhelpafrica.org\\\/ie\\\/tag\\\/management\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/selfhelpafrica.org\\\/ie\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"management\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/selfhelpafrica.org\\\/ie\\\/#website\",\"url\":\"https:\\\/\\\/selfhelpafrica.org\\\/ie\\\/\",\"name\":\"Self Help Africa\",\"description\":\"Farming for Africa&#039;s Future\",\"publisher\":{\"@id\":\"https:\\\/\\\/selfhelpafrica.org\\\/ie\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/selfhelpafrica.org\\\/ie\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/selfhelpafrica.org\\\/ie\\\/#organization\",\"name\":\"Self Help Africa\",\"url\":\"https:\\\/\\\/selfhelpafrica.org\\\/ie\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/selfhelpafrica.org\\\/ie\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/selfhelpafrica.org\\\/ie\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/12\\\/Untitled-design-1.png\",\"contentUrl\":\"https:\\\/\\\/selfhelpafrica.org\\\/ie\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2023\\\/12\\\/Untitled-design-1.png\",\"width\":1400,\"height\":900,\"caption\":\"Self Help Africa\"},\"image\":{\"@id\":\"https:\\\/\\\/selfhelpafrica.org\\\/ie\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SelfHelpAfrica\\\/\",\"https:\\\/\\\/x.com\\\/selfhelpafrica\",\"https:\\\/\\\/www.instagram.com\\\/selfhelpafrica\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/selfhelpafrica\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/SelfHelpAfricaTV\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"management Archives - Self Help Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/selfhelpafrica.org\/ie\/tag\/management\/","og_locale":"en_GB","og_type":"article","og_title":"management Archives","og_url":"https:\/\/selfhelpafrica.org\/ie\/tag\/management\/","og_site_name":"Self Help Africa","twitter_card":"summary_large_image","twitter_site":"@selfhelpafrica","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/selfhelpafrica.org\/ie\/tag\/management\/","url":"https:\/\/selfhelpafrica.org\/ie\/tag\/management\/","name":"management Archives - Self Help Africa","isPartOf":{"@id":"https:\/\/selfhelpafrica.org\/ie\/#website"},"breadcrumb":{"@id":"https:\/\/selfhelpafrica.org\/ie\/tag\/management\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/selfhelpafrica.org\/ie\/tag\/management\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/selfhelpafrica.org\/ie\/"},{"@type":"ListItem","position":2,"name":"management"}]},{"@type":"WebSite","@id":"https:\/\/selfhelpafrica.org\/ie\/#website","url":"https:\/\/selfhelpafrica.org\/ie\/","name":"Self Help Africa","description":"Farming for Africa&#039;s Future","publisher":{"@id":"https:\/\/selfhelpafrica.org\/ie\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/selfhelpafrica.org\/ie\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/selfhelpafrica.org\/ie\/#organization","name":"Self Help Africa","url":"https:\/\/selfhelpafrica.org\/ie\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/selfhelpafrica.org\/ie\/#\/schema\/logo\/image\/","url":"https:\/\/selfhelpafrica.org\/ie\/wp-content\/uploads\/sites\/4\/2023\/12\/Untitled-design-1.png","contentUrl":"https:\/\/selfhelpafrica.org\/ie\/wp-content\/uploads\/sites\/4\/2023\/12\/Untitled-design-1.png","width":1400,"height":900,"caption":"Self Help Africa"},"image":{"@id":"https:\/\/selfhelpafrica.org\/ie\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SelfHelpAfrica\/","https:\/\/x.com\/selfhelpafrica","https:\/\/www.instagram.com\/selfhelpafrica\/","https:\/\/www.linkedin.com\/company\/selfhelpafrica\/","https:\/\/www.youtube.com\/user\/SelfHelpAfricaTV"]}]}},"_links":{"self":[{"href":"https:\/\/selfhelpafrica.org\/ie\/wp-json\/wp\/v2\/tags\/1189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/selfhelpafrica.org\/ie\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/selfhelpafrica.org\/ie\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/selfhelpafrica.org\/ie\/wp-json\/wp\/v2\/posts?tags=1189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}